{"id":1920,"date":"2019-11-13T15:16:11","date_gmt":"2019-11-13T18:16:11","guid":{"rendered":"https:\/\/blog.contabilizei.com.br\/?p=1920"},"modified":"2025-02-11T11:48:41","modified_gmt":"2025-02-11T14:48:41","slug":"como-saber-o-cnae-de-uma-empresa","status":"publish","type":"post","link":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/","title":{"rendered":"Como saber o CNAE de uma empresa?"},"content":{"rendered":"\n<p><em>Como saber o CNAE de uma empresa? Se voc\u00ea est\u00e1 abrindo seu pr\u00f3prio neg\u00f3cio e tem d\u00favidas sobre qual classifica\u00e7\u00e3o defini melhor sua atividade, a solu\u00e7\u00e3o mais eficiente \u00e9 consultar um bom contador! <\/em><\/p>\n\n\n\n<p>Uma das <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/16-duvidas-que-todo-pequeno-empreendedor-tem\/\" rel=\"noreferrer noopener\" target=\"_blank\">d\u00favidas mais comuns entre os empreendedores<\/a> \u00e9 como saber o CNAE de uma empresa. Esse \u00e9 um tema importante, principalmente porque <strong>toda Pessoa Jur\u00eddica deve estar enquadrada<\/strong> em um dos c\u00f3digos dessa classifica\u00e7\u00e3o e esse \u00e9 um dos maiores fatores para decidir a al\u00edquota de imposto a ser paga.<\/p>\n\n\n\n<p>Neste conte\u00fado, mostramos para voc\u00ea o que exatamente \u00e9 o CNAE, como a classifica\u00e7\u00e3o se aplica, por que \u00e9 importante entender sobre o assunto e qual \u00e9 a diferen\u00e7a dos c\u00f3digos de servi\u00e7os. Ao final, ainda ensinamos como saber o CNAE de uma empresa.<\/p>\n\n\n\n<p>Continue a leitura para conferir!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"o-que-e-cnae\">O que \u00e9 CNAE?<\/h2>\n\n\n\n<p><a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/cnae\/\">CNAE<\/a> \u00e9 a sigla para Classifica\u00e7\u00e3o Nacional de Atividades Econ\u00f4micas. Trata-se de uma lista de c\u00f3digos que define as atividades exercidas por uma empresa.<\/p>\n\n\n\n<p>A lista \u00e9 bastante ampla e os c\u00f3digos s\u00e3o organizados por classes e subclasses. Durante a escolha, o empreendedor pode definir o c\u00f3digo de sua atividade principal e os c\u00f3digos de suas atividades secund\u00e1rias. Voc\u00ea pode consultar a <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/cnae\/\">tabela de CNAE<\/a> aqui no blog da Contabilizei!<\/p>\n\n\n\n<p>O principal objetivo do CNAE \u00e9 padronizar todos os c\u00f3digos de atividades no pa\u00eds e facilitar o <strong>enquadramento tribut\u00e1rio<\/strong> das empresas, o que melhora a fiscaliza\u00e7\u00e3o por parte do Governo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"quem-precisa-definir-cnae\">Quem precisa definir CNAE?<\/h2>\n\n\n\n<p>Todas as Pessoas Jur\u00eddicas s\u00e3o <strong>obrigadas<\/strong> a utilizar um c\u00f3digo CNAE, sejam elas empresas de presta\u00e7\u00e3o de servi\u00e7os, fabricantes de produtos, com\u00e9rcios, institui\u00e7\u00f5es sem fins lucrativos, entidades agr\u00edcolas, profissionais aut\u00f4nomos, etc.<\/p>\n\n\n\n<p>Durante o processo de abertura de um CNPJ, a Receita Federal exige que o c\u00f3digo seja informado na ficha cadastral da Pessoa Jur\u00eddica, documento necess\u00e1rio para obter o CNPJ. Portanto, se voc\u00ea pretende <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-abrir-empresa\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">abrir uma empresa<\/a>, <strong>precisar\u00e1 saber qual \u00e9 o CNAE mais adequado<\/strong>.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"por-que-saber-o-cnae-de-uma-empresa-e-importante\">Por que saber o CNAE de uma empresa \u00e9 importante?<\/h2>\n\n\n\n<p>\u00c9 importante saber que o CNAE n\u00e3o \u00e9 apenas uma burocracia a ser seguida. Al\u00e9m de facilitar a gest\u00e3o tribut\u00e1ria do Governo, ele tamb\u00e9m traz i<strong>mportantes reflexos para o seu neg\u00f3cio<\/strong>.<\/p><div id=\"conta-2827107478\" class=\"cta-bulk ga-cta-imagem-conteudo conta-cont-6p-cta-bulk conta-entity-placement\" style=\"margin-top: 30px;margin-bottom: 30px;\"><a href=\"https:\/\/www.contabilizei.com.br\/abrir-empresa\/\" aria-label=\"01\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2021\/07\/01.jpg?wsr\" alt=\"\"  srcset=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2021\/07\/01.jpg 615w, https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2021\/07\/01-300x146.jpg 300w\" sizes=\"(max-width: 615px) 100vw, 615px\" width=\"615\" height=\"300\"  style=\"display: inline-block;\" \/><\/a><\/div>\n\n\n\n<p>Veja os principais pontos sobre a classifica\u00e7\u00e3o nos t\u00f3picos abaixo!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Enquadramento Sindical<\/h3>\n\n\n\n<p>O CNAE escolhido determinar\u00e1 o sindicato patronal ao qual sua <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/o-que-e-microempresa-e-qual-a-diferenca-com-outros-tipos\/\" target=\"_blank\" rel=\"noreferrer noopener\">empresa ME<\/a> se enquadrar\u00e1. A escolha incorreta poder\u00e1 fazer com que seja obrigado a <strong>seguir conven\u00e7\u00f5es coletivas<\/strong> que n\u00e3o se aplicam ao neg\u00f3cio, bem como deixar de cumprir certas exig\u00eancias.<\/p>\n\n\n\n<p>Por exemplo, \u00e9 poss\u00edvel que exista um acordo que impe\u00e7a a realiza\u00e7\u00e3o de horas extras, que imponha benef\u00edcios, pisos salariais e outras exig\u00eancias sobre o trabalho prestado sob um determinado CNAE \u2014 e tais acordos podem n\u00e3o ser o melhor para o seu ramo de atua\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Enquadramento tribut\u00e1rio<\/h3>\n\n\n\n<p>Existem tr\u00eas <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/o-que-e-preciso-saber-sobre-regime-de-tributacao\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">regimes de tributa\u00e7\u00e3o<\/a> que diferenciam a forma de calcular os impostos de uma empresa. S\u00e3o eles o Lucro Real, o Lucro Presumido e o Simples Nacional.<\/p>\n\n\n\n<p>N\u00e3o h\u00e1 um enquadramento melhor que o outro. O que \u00e9 necess\u00e1rio \u00e9 ter o <strong>apoio de <\/strong><a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/o-que-levar-em-conta-na-hora-de-contratar-um-contador\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"><strong>contadores<\/strong><\/a> para que identifiquem o modelo <strong>mais vantajoso<\/strong> para seu neg\u00f3cio.<\/p>\n\n\n\n<p>Entretanto, n\u00e3o \u00e9 todo CNAE que pode se encaixar em qualquer regime tribut\u00e1rio. Por exemplo, se o <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/agendamento-simples-nacional\/\" rel=\"noreferrer noopener\" target=\"_blank\">enquadramento Simples Nacional<\/a> for o <strong>mais econ\u00f4mico<\/strong> para sua empresa, \u00e9 preciso escolher o c\u00f3digo que possibilite a op\u00e7\u00e3o ao regime.<\/p>\n\n\n\n<p>Se a escolha n\u00e3o for adequada, os \u00f3rg\u00e3os fiscalizadores poder\u00e3o considerar que voc\u00ea est\u00e1 tentando se esquivar de suas obriga\u00e7\u00f5es, e ent\u00e3o impor multas \u00e0 sua empresa.<\/p>\n\n\n\n<p>Confira em nossa ferramenta uma lista completa dos cnaes do simples nacional <a href=\"https:\/\/www.contabilizei.com.br\/consulta-cnae\/cnae-simples-nacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">cnae simples<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Desonera\u00e7\u00e3o da folha de pagamento<\/h3>\n\n\n\n<p>O Governo vem oferecendo alternativas para substituir a contribui\u00e7\u00e3o social sobre a folha de pagamento (INSS patronal de 20%) por outros pagamentos sobre o faturamento (receita bruta ou todos os ganhos decorrentes da atividade da empresa). Isso \u00e9 chamado de desonera\u00e7\u00e3o da folha de pagamento.<\/p>\n\n\n\n<p>Uma forma de determinar se o neg\u00f3cio poder\u00e1 fazer essa desonera\u00e7\u00e3o \u00e9 pelo CNAE da empresa, o que torna fundamental <strong>analisar criteriosamente<\/strong> a escolha do c\u00f3digo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"como-saber-o-cnae-de-uma-empresa-qual-a-diferenca-entre-cnae-e-codigo-de-servicos\">Como saber o CNAE de uma empresa: qual a diferen\u00e7a entre CNAE e C\u00f3digo de Servi\u00e7os?<\/h2>\n\n\n\n<p>\u00c9 muito comum que as pessoas confundam o C\u00f3digo de Servi\u00e7os com o CNAE, mas se tratam de conceitos bastante distintos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CNAE SIMPLES NACIONAL I Como consultar: ferramenta gratuita\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/cRFEYvvpmYM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>A Lista (ou <strong>C\u00f3digo de Servi\u00e7os)<\/strong> \u00e9 usada para identificar o <strong>tipo de servi\u00e7o<\/strong> prestado pelo seu neg\u00f3cio, conforme a <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/LCP\/Lcp116.htm\" rel=\"noreferrer noopener\" target=\"_blank\">Lei Complementar (LC) n.\u00ba 116\/2003<\/a>.<\/p>\n\n\n\n<p>Essa norma \u00e9 usada para definir se um servi\u00e7o ser\u00e1 tributado pelo Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/icms\/\" rel=\"noreferrer noopener\" target=\"_blank\">(<strong>ICMS<\/strong>)<\/a> ou pelo Imposto Sobre Servi\u00e7os <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/o-que-e-iss-e-como-calcular\/\" rel=\"noreferrer noopener\" target=\"_blank\">(<strong>ISS<\/strong>)<\/a>. Ela \u00e9 menos abrangente pelo fato de envolver apenas servi\u00e7os, e n\u00e3o \u00e9 usada para determinar o regime tribut\u00e1rio, o enquadramento sindical e a possibilidade de desonerar a folha de pagamento, como o CNAE.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"como-saber-se-um-cnae-pode-ser-enquadrado-no-simples-nacional\">Como saber se um CNAE pode ser enquadrado no Simples Nacional?<\/h2>\n\n\n\n<p>O Simples Nacional \u00e9 um regime exclusivo para pequenos neg\u00f3cios que faturam at\u00e9 R$ 4,8 milh\u00f5es anualmente. Sua principal vantagem consiste na <strong>simplifica\u00e7\u00e3o do recolhimento<\/strong> de diversos tributos e na <strong>diminui\u00e7\u00e3o da carga tribut\u00e1ria<\/strong>.<\/p>\n\n\n\n<p>Para saber se o CNAE da empresa pode aderir ao Simples, voc\u00ea pode consultar as <a href=\"http:\/\/receita.economia.gov.br\/acesso-rapido\/legislacao\/resolucoes-do-cgsn\" rel=\"noreferrer noopener\" target=\"_blank\">Resolu\u00e7\u00f5es do Comit\u00ea Gestor do Simples Nacional (CGSN)<\/a> ou conversar a respeito com seu contador. Essas normas, emitidas pela Receita Federal, trazem listas dos c\u00f3digos impeditivos \u00e0 ades\u00e3o ao regime.<\/p>\n\n\n\n<p>\u00c9 muito importante entender que nem sempre o Simples Nacional ser\u00e1 a op\u00e7\u00e3o mais vantajosa para sua empresa. Por isso, \u00e9 fundamental que voc\u00ea recorra a um <a href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/contabilizei-e-confiavel\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">servi\u00e7o de contabilidade confi\u00e1vel<\/a>, para saber se os outros regimes s\u00e3o mais econ\u00f4micos ou n\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"como-saber-o-cnae-correto-de-uma-empresa\">Como saber o CNAE correto de uma empresa?<\/h2>\n\n\n\n<p>Para encontrar os CNAEs dispon\u00edveis para o seu neg\u00f3cio, basta usar nossa ferramenta <a href=\"https:\/\/www.contabilizei.com.br\/consulta-cnae\/\" target=\"_blank\" rel=\"noreferrer noopener\">consultor de CNAEs<\/a>, a forma mais f\u00e1cil, gratuita e completa de descobrir a atividade ideal para a sua empresa.<\/p>\n\n\n\n<p>O c\u00f3digo final deve ter 7 n\u00fameros e ser\u00e1 a sua CNAE-Fiscal. Por exemplo, se voc\u00ea tem uma hamburgueria artesanal, as escolhas ser\u00e3o as seguintes:<\/p>\n\n\n\n<ul>\n<li>se\u00e7\u00e3o:&nbsp;I \u2014 alojamento e alimenta\u00e7\u00e3o;<\/li>\n\n\n\n<li>divis\u00e3o: 56 \u2014 alimenta\u00e7\u00e3o;<\/li>\n\n\n\n<li>grupo: 56.1 restaurante e outros servi\u00e7os de alimenta\u00e7\u00e3o e bebida;<\/li>\n\n\n\n<li>classe: 56.11-2 \u2014 restaurante e outros estabelecimentos de servi\u00e7os de alimenta\u00e7\u00e3o e bebida;<\/li>\n\n\n\n<li>subclasse: <a href=\"https:\/\/www.contabilizei.com.br\/consulta-cnae\/alimentacao\/5611203-lanchonetes-casas-de-cha-de-sucos-e-similares\/\" target=\"_blank\" rel=\"noreferrer noopener\">5611-2\/03 \u2014 lanchonetes, casas de sucos, ch\u00e1s e similares.<\/a><\/li>\n<\/ul>\n\n\n\n<p>Esse CNAE engloba bares, cafeterias, casas de salgados ou doces, fast-foods, pastelarias e outros estabelecimentos de alimenta\u00e7\u00e3o sem servi\u00e7o completo (como de gar\u00e7om).<\/p>\n\n\n\n<p>para outras informa\u00e7\u00f5es voc\u00ea pode consultar o site do <a href=\"https:\/\/concla.ibge.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">IGBE Concla.<\/a><\/p>\n\n\n\n<p>Agora que voc\u00ea entendeu como saber o CNAE da sua empresa, j\u00e1 sabe que se trata de uma escolha crucial para recolher os impostos corretamente. E lembre-se de que \u00e9 fundamental consultar um servi\u00e7o de contabilidade para aconselh\u00e1-lo sobre quais a\u00e7\u00f5es tomar para <strong>diminuir erros<\/strong> e <strong>evitar problemas<\/strong>.<\/p>\n\n\n\n<p>Ficou com d\u00favidas e quer conversar com um especialista em como saber o CNAE de uma empresa? A Contabilizei tem uma equipe de contadores super qualificados para te ajudar! <a href=\"https:\/\/www.contabilizei.com.br\/abrir-empresa\/\" rel=\"noreferrer noopener\" target=\"_blank\">Fale com um especialista.<\/a><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<cite>Vai abrir uma empresa de consultoria? Saiba como escolher o <a href=\"https:\/\/www.contabilizei.com.br\/consulta-cnae\/cnae-consultoria\/\" target=\"_blank\" rel=\"noreferrer noopener\">CNAE para consultor<\/a><\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"quais-sao-os-riscos-de-uma-empresa-operar-com-servicos-diferentes-da-cnae\">Quais s\u00e3o os riscos de uma empresa operar com servi\u00e7os diferentes da CNAE?<\/h2>\n\n\n\n<p>Quem responde essa d\u00favida \u00e9 o Head de assuntos regulat\u00f3rios da Contabilizei, Diego Zacarias, em <a href=\"https:\/\/revistapegn.globo.com\/gestao\/noticia\/2024\/01\/mudanca-de-ramo-como-alterar-cnae-sem-precisar-modificar-cnpj-da-empresa.ghtml\" target=\"_blank\" rel=\"noreferrer noopener\">entrevista \u00e0 Revista Pequenas Empresas e Grandes Neg\u00f3cios<\/a>. &#8220;Quando a atua\u00e7\u00e3o de um empreendimento n\u00e3o reflete a atividade econ\u00f4mica registrada oficialmente, a empresa estar\u00e1 sujeita a diversos riscos, em maior ou menor grau&#8221;, alerta Zacarias. Conforme o especialista, a desconformidade pode acarretar as seguintes consequ\u00eancias:<\/p>\n\n\n\n<ul>\n<li>Multa e\/ou bloqueio das atividades por irregularidade no alvar\u00e1 de funcionamento e em outras licen\u00e7as;<\/li>\n\n\n\n<li>Desenquadramento do Simples Nacional;<\/li>\n\n\n\n<li>Cobran\u00e7a de valores corrigidos de impostos, acrescidos de multa e juros, que podem ser potencializados pela pr\u00e1tica de evas\u00e3o fiscal (sonega\u00e7\u00e3o de impostos),<\/li>\n\n\n\n<li>Multa por aus\u00eancia de registro nos \u00f3rg\u00e3os de classe, em caso de atividades regulamentadas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Como saber o CNAE de uma empresa? Se voc\u00ea est\u00e1 abrindo seu pr\u00f3prio neg\u00f3cio e tem d\u00favidas sobre qual classifica\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":62,"featured_media":11164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[235],"tags":[],"cta-tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como saber o CNAE de uma empresa? | Blog da Contabilizei<\/title>\n<meta name=\"description\" content=\"Descubra como saber o CNAE de uma empresa, essa \u00e9 uma das classifica\u00e7\u00f5es mais importantes de um neg\u00f3cio que impacta diretamente nos impostos. Saiba mais!\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como saber o CNAE de uma empresa? | Blog da Contabilizei\" \/>\n<meta property=\"og:description\" content=\"Descubra como saber o CNAE de uma empresa, essa \u00e9 uma das classifica\u00e7\u00f5es mais importantes de um neg\u00f3cio que impacta diretamente nos impostos. Saiba mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Contabilizei\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Contabilizei\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Contabilizei\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-13T18:16:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-11T14:48:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2019\/11\/como-saber-o-cnae-de-uma-empresa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vitor Torres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@contabilizei\" \/>\n<meta name=\"twitter:site\" content=\"@contabilizei\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vitor Torres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como saber o CNAE de uma empresa? | Blog da Contabilizei","description":"Descubra como saber o CNAE de uma empresa, essa \u00e9 uma das classifica\u00e7\u00f5es mais importantes de um neg\u00f3cio que impacta diretamente nos impostos. Saiba mais!","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/","og_locale":"pt_BR","og_type":"article","og_title":"Como saber o CNAE de uma empresa? | Blog da Contabilizei","og_description":"Descubra como saber o CNAE de uma empresa, essa \u00e9 uma das classifica\u00e7\u00f5es mais importantes de um neg\u00f3cio que impacta diretamente nos impostos. Saiba mais!","og_url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/","og_site_name":"Blog da Contabilizei","article_publisher":"https:\/\/www.facebook.com\/Contabilizei\/","article_author":"https:\/\/www.facebook.com\/Contabilizei\/","article_published_time":"2019-11-13T18:16:11+00:00","article_modified_time":"2025-02-11T14:48:41+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2019\/11\/como-saber-o-cnae-de-uma-empresa.jpg","type":"image\/jpeg"}],"author":"Vitor Torres","twitter_card":"summary_large_image","twitter_creator":"@contabilizei","twitter_site":"@contabilizei","twitter_misc":{"Escrito por":"Vitor Torres","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#article","isPartOf":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/"},"author":{"name":"Vitor Torres","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#\/schema\/person\/87b4deaa44cff57e9234db891c5f72c0"},"headline":"Como saber o CNAE de uma empresa?","datePublished":"2019-11-13T18:16:11+00:00","dateModified":"2025-02-11T14:48:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/"},"wordCount":1411,"commentCount":0,"publisher":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#organization"},"image":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2019\/11\/como-saber-o-cnae-de-uma-empresa.jpg?wsr","articleSection":["Escolha do CNAE"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/","url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/","name":"Como saber o CNAE de uma empresa? | Blog da Contabilizei","isPartOf":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#primaryimage"},"image":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2019\/11\/como-saber-o-cnae-de-uma-empresa.jpg?wsr","datePublished":"2019-11-13T18:16:11+00:00","dateModified":"2025-02-11T14:48:41+00:00","description":"Descubra como saber o CNAE de uma empresa, essa \u00e9 uma das classifica\u00e7\u00f5es mais importantes de um neg\u00f3cio que impacta diretamente nos impostos. Saiba mais!","breadcrumb":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#primaryimage","url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2019\/11\/como-saber-o-cnae-de-uma-empresa.jpg?wsr","contentUrl":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-content\/uploads\/2019\/11\/como-saber-o-cnae-de-uma-empresa.jpg?wsr","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/como-saber-o-cnae-de-uma-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/"},{"@type":"ListItem","position":2,"name":"Escolha do CNAE","item":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/escolha-do-cnae\/"},{"@type":"ListItem","position":3,"name":"Como saber o CNAE de uma empresa?"}]},{"@type":"WebSite","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#website","url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/","name":"Blog da Contabilizei","description":"Apoiando o empreendedorismo desde 2013","publisher":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#organization","name":"Contabilizei Contabilidade","url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Contabilizei Contabilidade"},"image":{"@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Contabilizei\/","https:\/\/x.com\/contabilizei","https:\/\/www.instagram.com\/contabilizei\/","https:\/\/www.linkedin.com\/company\/contabilizei\/","https:\/\/www.youtube.com\/channel\/UCNAlIbSjWxrDLDllQUug8dA","https:\/\/pt.wikipedia.org\/wiki\/Contabilizei"]},{"@type":"Person","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#\/schema\/person\/87b4deaa44cff57e9234db891c5f72c0","name":"Vitor Torres","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4d123a72e5de57b92b84e56ac1baa6f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d123a72e5de57b92b84e56ac1baa6f6?s=96&d=mm&r=g","caption":"Vitor Torres"},"description":"Vitor Torres \u00e9 fundador e presidente da Contabilizei desde 2013, quando iniciou uma revolu\u00e7\u00e3o ao liderar o movimento de desburocratiza\u00e7\u00e3o da contabilidade no pa\u00eds, tendo alcan\u00e7ado a lideran\u00e7a no segmento durante essa jornada. Hoje tem o prop\u00f3sito de simplificar a vida dos micros e pequenos empreendedores e fortalecer o futuro de cada um dos 100 mil clientes da companhia, transformando o cen\u00e1rio do empreendedorismo no Brasil. O executivo \u00e9 formado em Administra\u00e7\u00e3o pela Universidade Positivo, possui forma\u00e7\u00e3o executiva em Lideran\u00e7a em Escala pela INSEAD, realizou um MBA de Administra\u00e7\u00e3o e Neg\u00f3cios pela Columbia Business School e participou de um Programa de Lideran\u00e7a Executiva em Neg\u00f3cios pela Stanford University Graduate School of Business. Em 2016, foi selecionado como Empreendedor Endeavor. Re\u00fane experi\u00eancia na \u00e1rea de consultoria e an\u00e1lise de neg\u00f3cios, tendo apoiado de forma pioneira no desenvolvimento do ecossistema de startups.","sameAs":["http:\/\/contabilizei.com.br","https:\/\/www.facebook.com\/Contabilizei\/","https:\/\/www.instagram.com\/contabilizei\/","https:\/\/www.linkedin.com\/company\/contabilizei\/","https:\/\/www.youtube.com\/channel\/UCNAlIbSjWxrDLDllQUug8dA"],"url":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/autor\/vitor-torres\/"}]}},"_links":{"self":[{"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/posts\/1920"}],"collection":[{"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/comments?post=1920"}],"version-history":[{"count":0,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/posts\/1920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/media\/11164"}],"wp:attachment":[{"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/media?parent=1920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/categories?post=1920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/tags?post=1920"},{"taxonomy":"cta-tags","embeddable":true,"href":"https:\/\/www.contabilizei.com.br\/contabilidade-online\/wp-json\/wp\/v2\/cta-tags?post=1920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}